{"id":39136,"date":"2017-12-29T10:00:06","date_gmt":"2017-12-29T12:00:06","guid":{"rendered":"http:\/\/folhapopular.info\/?p=39136"},"modified":"2017-12-29T08:06:11","modified_gmt":"2017-12-29T10:06:11","slug":"prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/","title":{"rendered":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde"},"content":{"rendered":"<p>As reparti\u00e7\u00f5es p\u00fablicas municipais de Estrela n\u00e3o atendem na pr\u00f3xima sexta-feira, dia 29 de dezembro, no turno da tarde. O prefeito em exerc\u00edcio Valmor Griebeler assinou decreto fixando ponto facultativo nesta data. Alguns servi\u00e7os, no entanto, ser\u00e3o mantidos. A Secretaria da Educa\u00e7\u00e3o avisa que o atendimento \u00e0s crian\u00e7as ser\u00e1 normal nas Escolas de Educa\u00e7\u00e3o infantil.<\/p>\n<p>A Secretaria da Sa\u00fade informa que na sexta-feira o Posto de Sa\u00fade Central, localizado na Rua Coronel Brito, vai atender at\u00e9 as 18h. As demais unidades tamb\u00e9m ter\u00e3o expediente normal, nos hor\u00e1rios de costume. A \u00e1rea administrativa da pasta, no entanto, vai atender somente na parte da manh\u00e3, at\u00e9 as 11h30min, como as demais reparti\u00e7\u00f5es municipais.<\/p>\n<p>J\u00e1 o recolhimento de lixo ser\u00e1 feito normalmente na sexta-feira e no s\u00e1bado. No dia 31(domingo, v\u00e9spera de Ano Novo) vai haver coleta de lixo seco e org\u00e2nico das 14h \u00e0s 16h, somente no Centro, hospital e Avenida Rio Branco. Nos demais bairros o servi\u00e7o n\u00e3o ser\u00e1 realizado.<br \/>\nNo dia 1\u00ba de janeiro (segunda-feira) tamb\u00e9m n\u00e3o haver\u00e1 coleta. O roteiro que seria realizado nesta data, tanto para a coleta do lixo seco quanto do org\u00e2nico, ser\u00e1 em 2 de janeiro, durante o dia, conforme cronograma a seguir:<br \/>\n&#8211; Lixo seco: Novo Para\u00edso, Lenz, Linha Geraldo, Linha Wink, S\u00e3o Jac\u00f3, Gl\u00f3ria, Porongos, Santa Rita, Cost\u00e3o, Ch\u00e1 da \u00cdndia, Roncador, Centro, hospital e Avenida Rio Branco;<br \/>\n&#8211; Lixo org\u00e2nico &#8211; Cristo Rei, Auxiliadora, Chacrinha, Alto da Bronze, Cohab II, Imigrantes, Estados, Moinhos, Loteamento Marmitt, Ind\u00fastrias, Oriental, Pinheiros, Boa Uni\u00e3o, Loteamento Popular, S\u00e3o Jos\u00e9, Cost\u00e3o, Centro, hospital e Avenida Rio Branco.<br \/>\nA secretaria pede aos moradores aten\u00e7\u00e3o para o hor\u00e1rio, a fim de evitar que os res\u00edduos fiquem acumulados nas vias p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As reparti\u00e7\u00f5es p\u00fablicas municipais de Estrela n\u00e3o atendem na pr\u00f3xima sexta-feira, dia 29 de dezembro, no turno da tarde. O prefeito em exerc\u00edcio Valmor Griebeler assinou decreto fixando ponto facultativo nesta data. Alguns servi\u00e7os, no entanto, ser\u00e3o mantidos. A Secretaria da Educa\u00e7\u00e3o avisa que o atendimento \u00e0s crian\u00e7as ser\u00e1 normal nas Escolas de Educa\u00e7\u00e3o infantil. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[8,1872],"class_list":["post-39136","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","tag-estrela","tag-ponto-facultativo","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"As reparti\u00e7\u00f5es p\u00fablicas municipais de Estrela n\u00e3o atendem na pr\u00f3xima sexta-feira, dia 29 de dezembro, no turno da tarde. O prefeito em exerc\u00edcio Valmor Griebeler assinou decreto fixando ponto facultativo nesta data. Alguns servi\u00e7os, no entanto, ser\u00e3o mantidos. A Secretaria da Educa\u00e7\u00e3o avisa que o atendimento \u00e0s crian\u00e7as ser\u00e1 normal nas Escolas de Educa\u00e7\u00e3o infantil. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-29T12:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde\",\"datePublished\":\"2017-12-29T12:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/\"},\"wordCount\":323,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Not\u00edcias_SITE-1-e1543404686907.jpg\",\"keywords\":[\"Estrela\",\"Ponto Facultativo\"],\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/\",\"name\":\"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Not\u00edcias_SITE-1-e1543404686907.jpg\",\"datePublished\":\"2017-12-29T12:00:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Not\u00edcias_SITE-1-e1543404686907.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Not\u00edcias_SITE-1-e1543404686907.jpg\",\"width\":800,\"height\":514,\"caption\":\"Cadastro reserva ser\u00e1 para cinco \u00e1reas de atua\u00e7\u00e3o nas salas de aula\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/29\\\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular","og_description":"As reparti\u00e7\u00f5es p\u00fablicas municipais de Estrela n\u00e3o atendem na pr\u00f3xima sexta-feira, dia 29 de dezembro, no turno da tarde. O prefeito em exerc\u00edcio Valmor Griebeler assinou decreto fixando ponto facultativo nesta data. Alguns servi\u00e7os, no entanto, ser\u00e3o mantidos. A Secretaria da Educa\u00e7\u00e3o avisa que o atendimento \u00e0s crian\u00e7as ser\u00e1 normal nas Escolas de Educa\u00e7\u00e3o infantil. [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/","og_site_name":"Folha Popular","article_published_time":"2017-12-29T12:00:06+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde","datePublished":"2017-12-29T12:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/"},"wordCount":323,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","keywords":["Estrela","Ponto Facultativo"],"articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/","name":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","datePublished":"2017-12-29T12:00:06+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","width":800,"height":514,"caption":"Cadastro reserva ser\u00e1 para cinco \u00e1reas de atua\u00e7\u00e3o nas salas de aula"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/29\/prefeitura-de-estrela-fara-ponto-facultativo-hoje-a-tarde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de Estrela far\u00e1 ponto facultativo hoje \u00e0 tarde"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/06\/Not\u00edcias_SITE-1-e1543404686907.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/39136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=39136"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/39136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/31867"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=39136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=39136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=39136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}