{"id":40797,"date":"2018-02-15T10:21:34","date_gmt":"2018-02-15T12:21:34","guid":{"rendered":"http:\/\/folhapopular.info\/?p=40797"},"modified":"2018-02-15T10:22:12","modified_gmt":"2018-02-15T12:22:12","slug":"engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/","title":{"rendered":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386"},"content":{"rendered":"<p>Um engavetamento que envolveu cinco ve\u00edculos deixou uma pessoa ferida, por volta das 8h20min da manh\u00e3 desta quinta-feira (15\/02), no Km 343,1 da BR-386, imedia\u00e7\u00f5es do Country Clube e do acesso ao Bairro Olarias, em Lajeado.\u00a0O tr\u00e2nsito ficou lento at\u00e9 o final do atendimento, por volta das 09h30min.<\/p>\n<p>O condutor de uma GM Montana, placas de Lajeado, trafegava no sentido interior-capital, quando freou o ve\u00edculo devido \u00e0 lentid\u00e3o do tr\u00e2nsito \u00e0 sua frente. O motorista de um Ford Cargo, emplacado em Fontoura Xavier, que vinha logo atr\u00e1s da Montana, n\u00e3o conseguiu frear a tempo e colidiu violentamente na traseira da Montana.<\/p>\n<p>Ap\u00f3s o choque, a Montana ainda foi arrastada para frente, colidindo na traseira de uma MMC L200 Triton, emplacada em Saldanha Marinho. Esta, por sua vez, colidiu na traseira de um VW Polo, tamb\u00e9m com placa de Saldanha Marinho. O condutor de um quinto ve\u00edculo, um GM Vectra de Lajeado, acabou colidindo na traseira do caminh\u00e3o.<\/p>\n<p>Apenas o motorista da Montana, de 29 anos, teve ferimentos leves, sendo encaminhado pelo Samu ao Hospital Bruno Born, em Lajedo. Os demais ocupantes dos ve\u00edculos ficaram ilesos.<\/p>\n<figure id=\"attachment_40800\" aria-describedby=\"caption-attachment-40800\" style=\"width: 713px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40800\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43.jpeg\" alt=\"\" width=\"713\" height=\"468\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43.jpeg 713w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43-300x197.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43-696x457.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.05.43-640x420.jpeg 640w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/><\/a><figcaption id=\"caption-attachment-40800\" class=\"wp-caption-text\">Cinco ve\u00edculos estiveram envolvidos no engavetamento em Lajeado<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Um engavetamento que envolveu cinco ve\u00edculos deixou uma pessoa ferida, por volta das 8h20min da manh\u00e3 desta quinta-feira (15\/02), no Km 343,1 da BR-386, imedia\u00e7\u00f5es do Country Clube e do acesso ao Bairro Olarias, em Lajeado.\u00a0O tr\u00e2nsito ficou lento at\u00e9 o final do atendimento, por volta das 09h30min. O condutor de uma GM Montana, placas [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":40799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,7],"tags":[1652,91,27],"class_list":["post-40797","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","category-seguranca","tag-acidente-com-lesoes","tag-br-386","tag-lajeado","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Um engavetamento que envolveu cinco ve\u00edculos deixou uma pessoa ferida, por volta das 8h20min da manh\u00e3 desta quinta-feira (15\/02), no Km 343,1 da BR-386, imedia\u00e7\u00f5es do Country Clube e do acesso ao Bairro Olarias, em Lajeado.\u00a0O tr\u00e2nsito ficou lento at\u00e9 o final do atendimento, por volta das 09h30min. O condutor de uma GM Montana, placas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-15T12:21:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-15T12:22:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386\",\"datePublished\":\"2018-02-15T12:21:34+00:00\",\"dateModified\":\"2018-02-15T12:22:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/\"},\"wordCount\":222,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg\",\"keywords\":[\"Acidente com Les\u00f5es\",\"BR-386\",\"Lajeado\"],\"articleSection\":[\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/\",\"name\":\"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg\",\"datePublished\":\"2018-02-15T12:21:34+00:00\",\"dateModified\":\"2018-02-15T12:22:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg\",\"width\":1024,\"height\":768,\"caption\":\"Montana ficou destru\u00edda ap\u00f3s o impacto, mas condutor teve les\u00f5es leves\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/02\\\/15\\\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/","og_locale":"pt_BR","og_type":"article","og_title":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular","og_description":"Um engavetamento que envolveu cinco ve\u00edculos deixou uma pessoa ferida, por volta das 8h20min da manh\u00e3 desta quinta-feira (15\/02), no Km 343,1 da BR-386, imedia\u00e7\u00f5es do Country Clube e do acesso ao Bairro Olarias, em Lajeado.\u00a0O tr\u00e2nsito ficou lento at\u00e9 o final do atendimento, por volta das 09h30min. O condutor de uma GM Montana, placas [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/","og_site_name":"Folha Popular","article_published_time":"2018-02-15T12:21:34+00:00","article_modified_time":"2018-02-15T12:22:12+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386","datePublished":"2018-02-15T12:21:34+00:00","dateModified":"2018-02-15T12:22:12+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/"},"wordCount":222,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","keywords":["Acidente com Les\u00f5es","BR-386","Lajeado"],"articleSection":["Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/","name":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386 - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","datePublished":"2018-02-15T12:21:34+00:00","dateModified":"2018-02-15T12:22:12+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","width":1024,"height":768,"caption":"Montana ficou destru\u00edda ap\u00f3s o impacto, mas condutor teve les\u00f5es leves"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/02\/15\/engavetamento-de-cinco-veiculos-deixa-um-ferido-na-br-386\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Engavetamento de cinco ve\u00edculos deixa um ferido na BR-386"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-10.00.36.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/40797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=40797"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/40797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/40799"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=40797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=40797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=40797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}