{"id":42441,"date":"2018-04-12T08:36:53","date_gmt":"2018-04-12T11:36:53","guid":{"rendered":"http:\/\/folhapopular.info\/?p=42441"},"modified":"2018-04-12T08:38:56","modified_gmt":"2018-04-12T11:38:56","slug":"bombeiros-voluntarios-combatem-incendio-veicular-em-paverama","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/","title":{"rendered":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama"},"content":{"rendered":"<p>O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia foi acionado para atender uma ocorr\u00eancia de inc\u00eandio veicular, na Localidade de Morro Bonito, em Paverama. Segundo os bombeiros, o ve\u00edculo Santana com placa de Paverama estava estacionado na Rua Alfredo Follmer por volta das 20h desta quarta-feira (11\/04), quando iniciou o fogo. As causas do inc\u00eandio s\u00e3o desconhecidas e nenhuma pessoa ficou ferida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia foi acionado para atender uma ocorr\u00eancia de inc\u00eandio veicular, na Localidade de Morro Bonito, em Paverama. Segundo os bombeiros, o ve\u00edculo Santana com placa de Paverama estava estacionado na Rua Alfredo Follmer por volta das 20h desta quarta-feira (11\/04), quando iniciou o fogo. As causas do inc\u00eandio s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[2534,1309,46],"class_list":["post-42441","post","type-post","status-publish","format-standard","has-post-thumbnail","category-seguranca","tag-bombeiros-voluntarios-de-teutonnia","tag-incendio-veicular","tag-paverama","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia foi acionado para atender uma ocorr\u00eancia de inc\u00eandio veicular, na Localidade de Morro Bonito, em Paverama. Segundo os bombeiros, o ve\u00edculo Santana com placa de Paverama estava estacionado na Rua Alfredo Follmer por volta das 20h desta quarta-feira (11\/04), quando iniciou o fogo. As causas do inc\u00eandio s\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T11:36:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-12T11:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama\",\"datePublished\":\"2018-04-12T11:36:53+00:00\",\"dateModified\":\"2018-04-12T11:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/\"},\"wordCount\":76,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"keywords\":[\"Bombeiros Volunt\u00e1rios de Teut\u00f4nnia\",\"Inc\u00eandio Veicular\",\"Paverama\"],\"articleSection\":[\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/\",\"name\":\"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"datePublished\":\"2018-04-12T11:36:53+00:00\",\"dateModified\":\"2018-04-12T11:38:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/04\\\/12\\\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/","og_locale":"pt_BR","og_type":"article","og_title":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular","og_description":"O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia foi acionado para atender uma ocorr\u00eancia de inc\u00eandio veicular, na Localidade de Morro Bonito, em Paverama. Segundo os bombeiros, o ve\u00edculo Santana com placa de Paverama estava estacionado na Rua Alfredo Follmer por volta das 20h desta quarta-feira (11\/04), quando iniciou o fogo. As causas do inc\u00eandio s\u00e3o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/","og_site_name":"Folha Popular","article_published_time":"2018-04-12T11:36:53+00:00","article_modified_time":"2018-04-12T11:38:56+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama","datePublished":"2018-04-12T11:36:53+00:00","dateModified":"2018-04-12T11:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/"},"wordCount":76,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","keywords":["Bombeiros Volunt\u00e1rios de Teut\u00f4nnia","Inc\u00eandio Veicular","Paverama"],"articleSection":["Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/","name":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","datePublished":"2018-04-12T11:36:53+00:00","dateModified":"2018-04-12T11:38:56+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/04\/12\/bombeiros-voluntarios-combatem-incendio-veicular-em-paverama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Bombeiros Volunt\u00e1rios combatem inc\u00eandio veicular em Paverama"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/42441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=42441"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/42441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/31970"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=42441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=42441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=42441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}