{"id":46131,"date":"2018-07-13T14:49:38","date_gmt":"2018-07-13T17:49:38","guid":{"rendered":"http:\/\/folhapopular.info\/?p=46131"},"modified":"2018-07-13T14:49:38","modified_gmt":"2018-07-13T17:49:38","slug":"rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/","title":{"rendered":"Rotary promove galinhada solid\u00e1ria em  benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios"},"content":{"rendered":"<p>Os integrantes do Interact, atrav\u00e9s do Rotary Teut\u00f4nia, promovem neste s\u00e1bado (14\/07) uma galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia. O evento tem in\u00edcio \u00e0s 11h com apresenta\u00e7\u00e3o de dois v\u00eddeos para mostrar a comunidade o que \u00e9 o grupo de Aspirantes dos Bombeiros e o grupo do Interact. Em seguida, ser\u00e1 servida a galinhada para os que v\u00e3o almo\u00e7ar no local e tamb\u00e9m entregue aos que v\u00e3o levar para casa.<\/p>\n<p>O evento ser\u00e1 realizado no Centro de Tradi\u00e7\u00f5es Ga\u00fachas (CTG) Rinc\u00e3o das Coxilhas, no Bairro Languiru. O valor do ingresso adulto custa R$ 20,00. Crian\u00e7as a partir de 7 anos \u00e9 R$ 10,00 e abaixo de 6 anos n\u00e3o pagam ingresso. Os ingressos podem ser adquiridos com integrantes do Interact (Rotary) e integrantes do grupo de Aspirantes do Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os integrantes do Interact, atrav\u00e9s do Rotary Teut\u00f4nia, promovem neste s\u00e1bado (14\/07) uma galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia. O evento tem in\u00edcio \u00e0s 11h com apresenta\u00e7\u00e3o de dois v\u00eddeos para mostrar a comunidade o que \u00e9 o grupo de Aspirantes dos Bombeiros e o grupo do Interact. Em seguida, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":46132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[354,3068,3067,274,26],"class_list":["post-46131","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-bombeiros-voluntarios","tag-cbv","tag-galinhada-solidaria","tag-rotary","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Os integrantes do Interact, atrav\u00e9s do Rotary Teut\u00f4nia, promovem neste s\u00e1bado (14\/07) uma galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia. O evento tem in\u00edcio \u00e0s 11h com apresenta\u00e7\u00e3o de dois v\u00eddeos para mostrar a comunidade o que \u00e9 o grupo de Aspirantes dos Bombeiros e o grupo do Interact. Em seguida, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-13T17:49:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios\",\"datePublished\":\"2018-07-13T17:49:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/\"},\"wordCount\":167,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg\",\"keywords\":[\"Bombeiros Volunt\u00e1rios\",\"CBV\",\"Galinhada Solid\u00e1ria\",\"Rotary\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/\",\"name\":\"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg\",\"datePublished\":\"2018-07-13T17:49:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/07\\\/13\\\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/","og_locale":"pt_BR","og_type":"article","og_title":"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular","og_description":"Os integrantes do Interact, atrav\u00e9s do Rotary Teut\u00f4nia, promovem neste s\u00e1bado (14\/07) uma galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia. O evento tem in\u00edcio \u00e0s 11h com apresenta\u00e7\u00e3o de dois v\u00eddeos para mostrar a comunidade o que \u00e9 o grupo de Aspirantes dos Bombeiros e o grupo do Interact. Em seguida, [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/","og_site_name":"Folha Popular","article_published_time":"2018-07-13T17:49:38+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios","datePublished":"2018-07-13T17:49:38+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/"},"wordCount":167,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","keywords":["Bombeiros Volunt\u00e1rios","CBV","Galinhada Solid\u00e1ria","Rotary","Teut\u00f4nia"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/","name":"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","datePublished":"2018-07-13T17:49:38+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/07\/13\/rotary-promove-galinhada-solidaria-em-beneficio-ao-corpo-de-bombeiros-voluntarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Rotary promove galinhada solid\u00e1ria em benef\u00edcio ao Corpo de Bombeiros Volunt\u00e1rios"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-10-at-10.35.47-e1531504168666.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/46131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=46131"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/46131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/46132"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=46131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=46131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=46131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}