{"id":48445,"date":"2018-10-01T07:24:20","date_gmt":"2018-10-01T10:24:20","guid":{"rendered":"http:\/\/folhapopular.info\/?p=48445"},"modified":"2018-10-01T07:34:26","modified_gmt":"2018-10-01T10:34:26","slug":"homem-e-preso-no-bairro-languiru-em-teutonia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/","title":{"rendered":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia"},"content":{"rendered":"<p>Por volta da 00h10min desta segunda-feira (01\/10), um homem foi abordado pela Brigada Militar de Teut\u00f4nia, na Rua Lauro Dickel, no Bairro Languiru.<\/p>\n<p>Foi constatado que o indiv\u00edduo, de 38 anos, possui um mandado de pris\u00e3o em Para\u00edba.<\/p>\n<p>Ele foi encaminhado \u00e0 DP de Lajeado e transferido para o Estado onde recebeu o mandado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta da 00h10min desta segunda-feira (01\/10), um homem foi abordado pela Brigada Militar de Teut\u00f4nia, na Rua Lauro Dickel, no Bairro Languiru. Foi constatado que o indiv\u00edduo, de 38 anos, possui um mandado de pris\u00e3o em Para\u00edba. Ele foi encaminhado \u00e0 DP de Lajeado e transferido para o Estado onde recebeu o mandado.<\/p>\n","protected":false},"author":8,"featured_media":31970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,7],"tags":[217,251,2974,26],"class_list":["post-48445","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","category-seguranca","tag-bairro-languiru","tag-brigada-militar","tag-mandado-de-prisao","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Por volta da 00h10min desta segunda-feira (01\/10), um homem foi abordado pela Brigada Militar de Teut\u00f4nia, na Rua Lauro Dickel, no Bairro Languiru. Foi constatado que o indiv\u00edduo, de 38 anos, possui um mandado de pris\u00e3o em Para\u00edba. Ele foi encaminhado \u00e0 DP de Lajeado e transferido para o Estado onde recebeu o mandado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T10:24:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-01T10:34:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia\",\"datePublished\":\"2018-10-01T10:24:20+00:00\",\"dateModified\":\"2018-10-01T10:34:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/\"},\"wordCount\":64,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"keywords\":[\"Bairro Languiru\",\"Brigada Militar\",\"Mandado de pris\u00e3o\",\"Teut\u00f4nia\"],\"articleSection\":[\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/\",\"name\":\"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"datePublished\":\"2018-10-01T10:24:20+00:00\",\"dateModified\":\"2018-10-01T10:34:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/01\\\/homem-e-preso-no-bairro-languiru-em-teutonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/","og_locale":"pt_BR","og_type":"article","og_title":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular","og_description":"Por volta da 00h10min desta segunda-feira (01\/10), um homem foi abordado pela Brigada Militar de Teut\u00f4nia, na Rua Lauro Dickel, no Bairro Languiru. Foi constatado que o indiv\u00edduo, de 38 anos, possui um mandado de pris\u00e3o em Para\u00edba. Ele foi encaminhado \u00e0 DP de Lajeado e transferido para o Estado onde recebeu o mandado.","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/","og_site_name":"Folha Popular","article_published_time":"2018-10-01T10:24:20+00:00","article_modified_time":"2018-10-01T10:34:26+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia","datePublished":"2018-10-01T10:24:20+00:00","dateModified":"2018-10-01T10:34:26+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/"},"wordCount":64,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","keywords":["Bairro Languiru","Brigada Militar","Mandado de pris\u00e3o","Teut\u00f4nia"],"articleSection":["Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/","name":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","datePublished":"2018-10-01T10:24:20+00:00","dateModified":"2018-10-01T10:34:26+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/01\/homem-e-preso-no-bairro-languiru-em-teutonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Homem \u00e9 preso no Bairro Languiru, em Teut\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/48445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=48445"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/48445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/31970"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=48445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=48445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=48445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}