{"id":49045,"date":"2018-10-18T13:00:01","date_gmt":"2018-10-18T16:00:01","guid":{"rendered":"http:\/\/folhapopular.info\/?p=49045"},"modified":"2018-10-18T09:32:30","modified_gmt":"2018-10-18T12:32:30","slug":"49045","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/","title":{"rendered":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa"},"content":{"rendered":"<p>Nesta ter\u00e7a-feira (16\/10), a Emater, em parceria com a Administra\u00e7\u00e3o Municipal de Carlos Barbosa, atrav\u00e9s da Secretaria da Sa\u00fade, promoveram o Dia de Campo. O evento, que ocorre anualmente, reuniu mais de 80 agricultoras, na Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia de Arcoverde.<br \/>\nCom o tema \u201cAlimenta\u00e7\u00e3o e Sa\u00fade\u201d, o Dia de Campo foi dividido em esta\u00e7\u00f5es, entre elas:\u00a0apresenta\u00e7\u00e3o do Rel\u00f3gio do Corpo Humano e Funcionamento dos \u00d3rg\u00e3os, apresentado pela enfermeira Carize Costa, Plantas Aliment\u00edcias n\u00e3o Convencionais \u2013 PANC&#8217;s, com a extensionista rural Jessica Zalamena, Produ\u00e7\u00e3o Org\u00e2nica, cujo tema foi abordado pelo assistente t\u00e9cnico regional, engenheiro agr\u00f4nomo Jo\u00e3o Villa e Plantas Medicinais, tratado pela extensionista rural Marisa Bortolini.<\/p>\n<p>Durante a abertura do evento, a extensionista rural\u00a0Ver\u00f4nica Bandeira Sim\u00f5es\u00a0destacou que h\u00e1 anos o Escrit\u00f3rio Municipal da Emater desenvolve um trabalho com plantas medicinais e arom\u00e1ticas, mencionando que muitas atividades s\u00e3o em parceria com a Administra\u00e7\u00e3o Municipal. O supervisor regional da Emater, Gilberto Bonatto, salientou a import\u00e2ncia de comer saudavelmente. \u201cJ\u00e1 tem pesquisas dizendo que os moradores da \u00e1rea rural est\u00e3o comendo semelhante aos da \u00e1rea urbana.\u201d, ressaltando que as coisas boas e saud\u00e1veis est\u00e3o presentes na \u00e1rea rural e \u00e9 preciso valorizar e aproveitar isso.<\/p>\n<p>A secret\u00e1ria da Sa\u00fade, Let\u00edcia Lusani, falou sobre a import\u00e2ncia de promover a sa\u00fade e a inclus\u00e3o social. \u201cEm 2016 come\u00e7amos de foma muito t\u00edmida a atividade nova com o rel\u00f3gio biol\u00f3gico na comunidade de Arcoverde. Nos anos seguintes, em 2017 e 2018, demos passos enormes na evolu\u00e7\u00e3o desta atividade, cada vez mais com a participa\u00e7\u00e3o de entidades parceiras, como a Emater, os t\u00e9cnicos que trabalham aqui na Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia e, principalmente, com o aux\u00edlio e apoio da comunidade.\u201d, frisou. Al\u00e9m disso, salientou que \u00e9 preciso manter uma pol\u00edtica de sa\u00fade que v\u00e1 ao encontro do preventivo. \u201cOs h\u00e1bitos, muitas vezes errados, refletem nas m\u00e1s condi\u00e7\u00f5es de sa\u00fade da comunidade.\u201d, alertou. Finalizou mencionando um dado alarmante, que \u00e9 a quantidade de medicamentos dispensados. Muitas vezes os mesmos s\u00e3o relacionados a falta de atividade f\u00edsica e falta de inclus\u00e3o de h\u00e1bitos saud\u00e1veis na rotina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira (16\/10), a Emater, em parceria com a Administra\u00e7\u00e3o Municipal de Carlos Barbosa, atrav\u00e9s da Secretaria da Sa\u00fade, promoveram o Dia de Campo. O evento, que ocorre anualmente, reuniu mais de 80 agricultoras, na Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia de Arcoverde. Com o tema \u201cAlimenta\u00e7\u00e3o e Sa\u00fade\u201d, o Dia de Campo foi dividido em [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":49046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[2121,30,3511],"class_list":["post-49045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","tag-alimentacao-saudavel","tag-carlos-barbosa","tag-dia-de-campo","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Nesta ter\u00e7a-feira (16\/10), a Emater, em parceria com a Administra\u00e7\u00e3o Municipal de Carlos Barbosa, atrav\u00e9s da Secretaria da Sa\u00fade, promoveram o Dia de Campo. O evento, que ocorre anualmente, reuniu mais de 80 agricultoras, na Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia de Arcoverde. Com o tema \u201cAlimenta\u00e7\u00e3o e Sa\u00fade\u201d, o Dia de Campo foi dividido em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-18T16:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa\",\"datePublished\":\"2018-10-18T16:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/\"},\"wordCount\":406,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2018_10_16_1539721303-e1539865908218.jpg\",\"keywords\":[\"Alimenta\u00e7\u00e3o Saud\u00e1vel\",\"Carlos Barbosa\",\"Dia de Campo\"],\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/\",\"name\":\"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2018_10_16_1539721303-e1539865908218.jpg\",\"datePublished\":\"2018-10-18T16:00:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2018_10_16_1539721303-e1539865908218.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2018_10_16_1539721303-e1539865908218.jpg\",\"width\":800,\"height\":533,\"caption\":\"Cr\u00e9dito da foto: Thais Cristina Formentini\\\/Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/10\\\/18\\\/49045\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/","og_locale":"pt_BR","og_type":"article","og_title":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular","og_description":"Nesta ter\u00e7a-feira (16\/10), a Emater, em parceria com a Administra\u00e7\u00e3o Municipal de Carlos Barbosa, atrav\u00e9s da Secretaria da Sa\u00fade, promoveram o Dia de Campo. O evento, que ocorre anualmente, reuniu mais de 80 agricultoras, na Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia de Arcoverde. Com o tema \u201cAlimenta\u00e7\u00e3o e Sa\u00fade\u201d, o Dia de Campo foi dividido em [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/","og_site_name":"Folha Popular","article_published_time":"2018-10-18T16:00:01+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa","datePublished":"2018-10-18T16:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/"},"wordCount":406,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","keywords":["Alimenta\u00e7\u00e3o Saud\u00e1vel","Carlos Barbosa","Dia de Campo"],"articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/","name":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","datePublished":"2018-10-18T16:00:01+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","width":800,"height":533,"caption":"Cr\u00e9dito da foto: Thais Cristina Formentini\/Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/10\/18\/49045\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Alimenta\u00e7\u00e3o Saud\u00e1vel foi tema do Dia de Campo em Carlos Barbosa"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/10\/2018_10_16_1539721303-e1539865908218.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/49045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=49045"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/49045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/49046"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=49045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=49045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=49045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}