{"id":49506,"date":"2018-11-10T18:24:24","date_gmt":"2018-11-10T20:24:24","guid":{"rendered":"http:\/\/folhapopular.info\/?p=49506"},"modified":"2018-11-12T15:08:39","modified_gmt":"2018-11-12T17:08:39","slug":"bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/","title":{"rendered":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia"},"content":{"rendered":"<p>A Brigada Militar prendeu dois ind\u00edviduos envolvidos no assalto a uma joalheria no Bairro Languiru, em Teut\u00f4nia. Por volta das 8h da manh\u00e3 deste s\u00e1bado (10\/11), entraram no estabelecimento localizado na Rua Arthur Pilz, ao lado da Rodovi\u00e1ria e anunciaram o assalto. Depois da a\u00e7\u00e3o, os criminosos fugiram em um Onix, cor branca, at\u00e9 o Bairro Alesgut, onde trocaram de carro e embarcaram em um Fiat Stilo cinza, indo em dire\u00e7\u00e3o a Estrela, pelo interior. A Brigada Militar realizou persegui\u00e7\u00e3o e, em Linha Wink \u2013 que fica na divisa de Teut\u00f4nia e Estrela, houve troca de tiros entre bandidos e policiais. Os bandidos abandonaram o carro e fugiram para uma lavoura de milho e matagais na localidade. Em seguida, um deles foi preso. Com o cerco policial montado, um segundo assaltante foi capturado. A pol\u00edcia recuperou ainda os produtos roubados e os dois ve\u00edculos utilizados na fuga. N\u00e3o se sabe ao certo se eram tr\u00eas ou quatro assaltantes. As buscas pelos outros assaltantes continuam. Os homens presos s\u00e3o de Teut\u00f4nia e de Porto Alegre. Tantos os presos, quanto os materiais recuperados foram apresentados na Delegacia de Pol\u00edcia de Pronto Atendimento, em Lajeado.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #tdi_1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"tdi_1\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 3<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-e1541881372229.jpeg\" title=\"Cr\u00e9dito da foto: Divulga\u00e7\u00e3o BM\"  data-caption=\"Um dos ve\u00edculos utilizados na fuga\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-560x420.jpeg\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-265x198.jpeg 265w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.28-e1541881372229.jpeg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Um dos ve\u00edculos utilizados na fuga<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-e1541881411615.jpeg\" title=\"Cr\u00e9dito da foto: Divulga\u00e7\u00e3o BM\"  data-caption=\"Ve\u00edculo utilizado na fuga tamb\u00e9m foi recuperado\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-560x420.jpeg\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-265x198.jpeg 265w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1-e1541881411615.jpeg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ve\u00edculo utilizado na fuga tamb\u00e9m foi recuperado<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-e1541881433817.jpeg\" title=\"Cr\u00e9dito da foto: Divulga\u00e7\u00e3o BM\"  data-caption=\"Produtos levados foram recuperados\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-560x420.jpeg\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-265x198.jpeg 265w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-14.21.27-e1541881433817.jpeg 800w\" sizes=\"(max-width: 560px) 100vw, 560px\" alt=\"\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Produtos levados foram recuperados<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n","protected":false},"excerpt":{"rendered":"<p>A Brigada Militar prendeu dois ind\u00edviduos envolvidos no assalto a uma joalheria no Bairro Languiru, em Teut\u00f4nia. Por volta das 8h da manh\u00e3 deste s\u00e1bado (10\/11), entraram no estabelecimento localizado na Rua Arthur Pilz, ao lado da Rodovi\u00e1ria e anunciaram o assalto. Depois da a\u00e7\u00e3o, os criminosos fugiram em um Onix, cor branca, at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":49507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3,7],"tags":[429,107,26],"class_list":["post-49506","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","category-seguranca","tag-assalto","tag-prisao","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Brigada Militar prendeu dois ind\u00edviduos envolvidos no assalto a uma joalheria no Bairro Languiru, em Teut\u00f4nia. Por volta das 8h da manh\u00e3 deste s\u00e1bado (10\/11), entraram no estabelecimento localizado na Rua Arthur Pilz, ao lado da Rodovi\u00e1ria e anunciaram o assalto. Depois da a\u00e7\u00e3o, os criminosos fugiram em um Onix, cor branca, at\u00e9 o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-10T20:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-12T17:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia\",\"datePublished\":\"2018-11-10T20:24:24+00:00\",\"dateModified\":\"2018-11-12T17:08:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/\"},\"wordCount\":227,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg\",\"keywords\":[\"Assalto\",\"Pris\u00e3o\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/\",\"name\":\"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg\",\"datePublished\":\"2018-11-10T20:24:24+00:00\",\"dateModified\":\"2018-11-12T17:08:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg\",\"width\":800,\"height\":450,\"caption\":\"Produtos levados foram recuperados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2018\\\/11\\\/10\\\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/","og_locale":"pt_BR","og_type":"article","og_title":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular","og_description":"A Brigada Militar prendeu dois ind\u00edviduos envolvidos no assalto a uma joalheria no Bairro Languiru, em Teut\u00f4nia. Por volta das 8h da manh\u00e3 deste s\u00e1bado (10\/11), entraram no estabelecimento localizado na Rua Arthur Pilz, ao lado da Rodovi\u00e1ria e anunciaram o assalto. Depois da a\u00e7\u00e3o, os criminosos fugiram em um Onix, cor branca, at\u00e9 o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/","og_site_name":"Folha Popular","article_published_time":"2018-11-10T20:24:24+00:00","article_modified_time":"2018-11-12T17:08:39+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia","datePublished":"2018-11-10T20:24:24+00:00","dateModified":"2018-11-12T17:08:39+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/"},"wordCount":227,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","keywords":["Assalto","Pris\u00e3o","Teut\u00f4nia"],"articleSection":["Destaques","Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/","url":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/","name":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","datePublished":"2018-11-10T20:24:24+00:00","dateModified":"2018-11-12T17:08:39+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","width":800,"height":450,"caption":"Produtos levados foram recuperados"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2018\/11\/10\/bm-prende-dois-envolvidos-e-recupera-mercadorias-levadas-em-assalto-a-joalheiria-em-teutonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"BM prende dois envolvidos e recupera mercadorias levadas em assalto a joalheiria em Teut\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2018\/11\/WhatsApp-Image-2018-11-10-at-15.20.06-e1541881351121.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/49506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=49506"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/49506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/49507"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=49506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=49506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=49506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}