{"id":54024,"date":"2019-03-04T07:04:36","date_gmt":"2019-03-04T10:04:36","guid":{"rendered":"http:\/\/folhapopular.info\/?p=54024"},"modified":"2019-03-04T07:10:13","modified_gmt":"2019-03-04T10:10:13","slug":"caso-de-maria-da-penha-e-registrado-no-bairro-canabarro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/","title":{"rendered":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Brigada Militar de Teut\u00f4nia atendeu um caso de Maria da Penha por volta das 23h30min deste domingo (03\/03), na Rua M\u00e1rio Scheaffer, no Bairro Canabarro. Uma mulher, de 56 anos, tinha medida protetiva contra o seu filho, de 30 anos. Mas ele violou esta medida e tentou entrar na resid\u00eancia. Detido, ele foi encaminhado para a DPPA de Lajeado, ap\u00f3s o registro, foi liberado.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Brigada Militar de Teut\u00f4nia atendeu um caso de Maria da Penha por volta das 23h30min deste domingo (03\/03), na Rua M\u00e1rio Scheaffer, no Bairro Canabarro. Uma mulher, de 56 anos, tinha medida protetiva contra o seu filho, de 30 anos. Mas ele violou esta medida e tentou entrar na resid\u00eancia. Detido, ele foi encaminhado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[216,1059,26],"class_list":["post-54024","post","type-post","status-publish","format-standard","has-post-thumbnail","category-seguranca","tag-bairro-canabarro","tag-maria-da-penha","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Brigada Militar de Teut\u00f4nia atendeu um caso de Maria da Penha por volta das 23h30min deste domingo (03\/03), na Rua M\u00e1rio Scheaffer, no Bairro Canabarro. Uma mulher, de 56 anos, tinha medida protetiva contra o seu filho, de 30 anos. Mas ele violou esta medida e tentou entrar na resid\u00eancia. Detido, ele foi encaminhado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-04T10:04:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-04T10:10:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro\",\"datePublished\":\"2019-03-04T10:04:36+00:00\",\"dateModified\":\"2019-03-04T10:10:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/\"},\"wordCount\":76,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"keywords\":[\"Bairro Canabarro\",\"Maria da Penha\",\"Teut\u00f4nia\"],\"articleSection\":[\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/\",\"name\":\"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"datePublished\":\"2019-03-04T10:04:36+00:00\",\"dateModified\":\"2019-03-04T10:10:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2019\\\/03\\\/04\\\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/","og_locale":"pt_BR","og_type":"article","og_title":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular","og_description":"A Brigada Militar de Teut\u00f4nia atendeu um caso de Maria da Penha por volta das 23h30min deste domingo (03\/03), na Rua M\u00e1rio Scheaffer, no Bairro Canabarro. Uma mulher, de 56 anos, tinha medida protetiva contra o seu filho, de 30 anos. Mas ele violou esta medida e tentou entrar na resid\u00eancia. Detido, ele foi encaminhado [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/","og_site_name":"Folha Popular","article_published_time":"2019-03-04T10:04:36+00:00","article_modified_time":"2019-03-04T10:10:13+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro","datePublished":"2019-03-04T10:04:36+00:00","dateModified":"2019-03-04T10:10:13+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/"},"wordCount":76,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","keywords":["Bairro Canabarro","Maria da Penha","Teut\u00f4nia"],"articleSection":["Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/","url":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/","name":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","datePublished":"2019-03-04T10:04:36+00:00","dateModified":"2019-03-04T10:10:13+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2019\/03\/04\/caso-de-maria-da-penha-e-registrado-no-bairro-canabarro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Caso de Maria da Penha \u00e9 registrado no Bairro Canabarro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/54024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=54024"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/54024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/31970"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=54024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=54024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=54024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}