{"id":63079,"date":"2020-01-06T16:40:25","date_gmt":"2020-01-06T19:40:25","guid":{"rendered":"https:\/\/folhapopular.info\/?p=63079"},"modified":"2020-01-06T16:40:28","modified_gmt":"2020-01-06T19:40:28","slug":"duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/","title":{"rendered":"Duas pessoas morrem em acidente na BR-386, em Triunfo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Duas pessoas morreram em um acidente de tr\u00e2nsito na BR-386, em Triunfo, na tarde desta segunda-feira (06\/01). O fato ocorreu por volta das 14h30, no km 408,8 da rodovia. Um autom\u00f3vel Renault Captur, de Porto Alegre, seguia no sentido interior x capital quando o condutor perdeu o controle do ve\u00edculo, saiu de pista e capotou. O condutor, de 59 anos, natural de Panambi, e um passageiro, de 30 anos, natural de Alegrete, faleceram no local. Eles estavam utilizado o cinto de seguran\u00e7a. Outros dois passageiros ficaram gravemente feridos e foram resgatados pela ambul\u00e2ncia da CCR Viasul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas pessoas morreram em um acidente de tr\u00e2nsito na BR-386, em Triunfo, na tarde desta segunda-feira (06\/01). O fato ocorreu por volta das 14h30, no km 408,8 da rodovia. Um autom\u00f3vel Renault Captur, de Porto Alegre, seguia no sentido interior x capital quando o condutor perdeu o controle do ve\u00edculo, saiu de pista e capotou. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":63080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3,7],"tags":[195,773],"class_list":["post-63079","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","category-seguranca","tag-acidente","tag-triunfo","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Duas pessoas morreram em um acidente de tr\u00e2nsito na BR-386, em Triunfo, na tarde desta segunda-feira (06\/01). O fato ocorreu por volta das 14h30, no km 408,8 da rodovia. Um autom\u00f3vel Renault Captur, de Porto Alegre, seguia no sentido interior x capital quando o condutor perdeu o controle do ve\u00edculo, saiu de pista e capotou. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-06T19:40:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-06T19:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Duas pessoas morrem em acidente na BR-386, em Triunfo\",\"datePublished\":\"2020-01-06T19:40:25+00:00\",\"dateModified\":\"2020-01-06T19:40:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/\"},\"wordCount\":106,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg\",\"keywords\":[\"Acidente\",\"Triunfo\"],\"articleSection\":[\"Destaques\",\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/\",\"name\":\"Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg\",\"datePublished\":\"2020-01-06T19:40:25+00:00\",\"dateModified\":\"2020-01-06T19:40:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/01\\\/06\\\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duas pessoas morrem em acidente na BR-386, em Triunfo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/","og_locale":"pt_BR","og_type":"article","og_title":"Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular","og_description":"Duas pessoas morreram em um acidente de tr\u00e2nsito na BR-386, em Triunfo, na tarde desta segunda-feira (06\/01). O fato ocorreu por volta das 14h30, no km 408,8 da rodovia. Um autom\u00f3vel Renault Captur, de Porto Alegre, seguia no sentido interior x capital quando o condutor perdeu o controle do ve\u00edculo, saiu de pista e capotou. [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/","og_site_name":"Folha Popular","article_published_time":"2020-01-06T19:40:25+00:00","article_modified_time":"2020-01-06T19:40:28+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Duas pessoas morrem em acidente na BR-386, em Triunfo","datePublished":"2020-01-06T19:40:25+00:00","dateModified":"2020-01-06T19:40:28+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/"},"wordCount":106,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","keywords":["Acidente","Triunfo"],"articleSection":["Destaques","Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/","url":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/","name":"Duas pessoas morrem em acidente na BR-386, em Triunfo - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","datePublished":"2020-01-06T19:40:25+00:00","dateModified":"2020-01-06T19:40:28+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2020\/01\/06\/duas-pessoas-morrem-em-acidente-na-br-386-em-triunfo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Duas pessoas morrem em acidente na BR-386, em Triunfo"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/01\/WhatsApp-Image-2020-01-06-at-15.39.03-e1578339496388.jpeg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/63079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=63079"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/63079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/63080"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=63079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=63079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=63079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}