{"id":64141,"date":"2020-02-06T07:22:54","date_gmt":"2020-02-06T10:22:54","guid":{"rendered":"https:\/\/folhapopular.info\/?p=64141"},"modified":"2020-02-06T07:22:55","modified_gmt":"2020-02-06T10:22:55","slug":"farmacia-e-assaltada-no-bairro-canabarro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/","title":{"rendered":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Uma farm\u00e1cia foi assaltada por volta das 20h40 desta quarta-feira, na Rua Carlos Arnt, Bairro Canabarro, em Teut\u00f4nia. Conforme a Brigada Militar, um indiv\u00edduo entrou no estabelecimento e anunciou o assalto, levando cerca de R$ 300,00 em dinheiro. Ele chegou e fugiu a p\u00e9, sem esconder rosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma farm\u00e1cia foi assaltada por volta das 20h40 desta quarta-feira, na Rua Carlos Arnt, Bairro Canabarro, em Teut\u00f4nia. Conforme a Brigada Militar, um indiv\u00edduo entrou no estabelecimento e anunciou o assalto, levando cerca de R$ 300,00 em dinheiro. Ele chegou e fugiu a p\u00e9, sem esconder rosto.<\/p>\n","protected":false},"author":8,"featured_media":58539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,7],"tags":[429,26],"class_list":["post-64141","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","category-seguranca","tag-assalto","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Uma farm\u00e1cia foi assaltada por volta das 20h40 desta quarta-feira, na Rua Carlos Arnt, Bairro Canabarro, em Teut\u00f4nia. Conforme a Brigada Militar, um indiv\u00edduo entrou no estabelecimento e anunciou o assalto, levando cerca de R$ 300,00 em dinheiro. Ele chegou e fugiu a p\u00e9, sem esconder rosto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T10:22:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T10:22:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro\",\"datePublished\":\"2020-02-06T10:22:54+00:00\",\"dateModified\":\"2020-02-06T10:22:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/\"},\"wordCount\":55,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"keywords\":[\"Assalto\",\"Teut\u00f4nia\"],\"articleSection\":[\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/\",\"name\":\"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"datePublished\":\"2020-02-06T10:22:54+00:00\",\"dateModified\":\"2020-02-06T10:22:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"width\":800,\"height\":563,\"caption\":\"Cr\u00e9dito da arte: J\u00falia Caroline Geib\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/02\\\/06\\\/farmacia-e-assaltada-no-bairro-canabarro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/","og_locale":"pt_BR","og_type":"article","og_title":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular","og_description":"Uma farm\u00e1cia foi assaltada por volta das 20h40 desta quarta-feira, na Rua Carlos Arnt, Bairro Canabarro, em Teut\u00f4nia. Conforme a Brigada Militar, um indiv\u00edduo entrou no estabelecimento e anunciou o assalto, levando cerca de R$ 300,00 em dinheiro. Ele chegou e fugiu a p\u00e9, sem esconder rosto.","og_url":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/","og_site_name":"Folha Popular","article_published_time":"2020-02-06T10:22:54+00:00","article_modified_time":"2020-02-06T10:22:55+00:00","og_image":[{"width":800,"height":563,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro","datePublished":"2020-02-06T10:22:54+00:00","dateModified":"2020-02-06T10:22:55+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/"},"wordCount":55,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","keywords":["Assalto","Teut\u00f4nia"],"articleSection":["Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/","url":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/","name":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","datePublished":"2020-02-06T10:22:54+00:00","dateModified":"2020-02-06T10:22:55+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","width":800,"height":563,"caption":"Cr\u00e9dito da arte: J\u00falia Caroline Geib"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2020\/02\/06\/farmacia-e-assaltada-no-bairro-canabarro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Farm\u00e1cia \u00e9 assaltada no Bairro Canabarro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/64141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=64141"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/64141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/58539"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=64141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=64141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=64141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}