{"id":73297,"date":"2020-09-06T14:59:44","date_gmt":"2020-09-06T17:59:44","guid":{"rendered":"https:\/\/folhapopular.info\/?p=73297"},"modified":"2020-09-06T15:11:16","modified_gmt":"2020-09-06T18:11:16","slug":"apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/","title":{"rendered":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O partido do PT realizou sua conven\u00e7\u00e3o na manh\u00e3 deste domingo (06\/09) em Westf\u00e1lia. Na ocasi\u00e3o, foi oficializada a candidatura do atual vereador Cl\u00e9cio Spellmeier (PT) como vice-prefeito do candidato a prefeito Joacir Ant\u00f4nio Docena (MDB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O MDB e o PDT, partidos coligados, realizaram suas conven\u00e7\u00f5es ontem. Os tr\u00eas partidos est\u00e3o aliados e compuseram a chapa majorit\u00e1ria com Docena e Spellmeier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a elei\u00e7\u00e3o proporcional (vereador), o PT lan\u00e7ou cinco candidatos a vereador, todos aprovados na conven\u00e7\u00e3o: Aline Sofia Schlieck, Rejane Ahlert Eggers, Claimar Domingos Kohl, Renato Gaspar Herbert e Valmor Endler.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O partido do PT realizou sua conven\u00e7\u00e3o na manh\u00e3 deste domingo (06\/09) em Westf\u00e1lia. Na ocasi\u00e3o, foi oficializada a candidatura do atual vereador Cl\u00e9cio Spellmeier (PT) como vice-prefeito do candidato a prefeito Joacir Ant\u00f4nio Docena (MDB). O MDB e o PDT, partidos coligados, realizaram suas conven\u00e7\u00f5es ontem. Os tr\u00eas partidos est\u00e3o aliados e compuseram a [&hellip;]<\/p>\n","protected":false},"author":553,"featured_media":73298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3553,3],"tags":[6126,6131,25],"class_list":["post-73297","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-eleicoes","category-geral","tag-convencoes","tag-pt","tag-westfalia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O partido do PT realizou sua conven\u00e7\u00e3o na manh\u00e3 deste domingo (06\/09) em Westf\u00e1lia. Na ocasi\u00e3o, foi oficializada a candidatura do atual vereador Cl\u00e9cio Spellmeier (PT) como vice-prefeito do candidato a prefeito Joacir Ant\u00f4nio Docena (MDB). O MDB e o PDT, partidos coligados, realizaram suas conven\u00e7\u00f5es ontem. Os tr\u00eas partidos est\u00e3o aliados e compuseram a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-06T17:59:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-06T18:11:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00falia Caroline Geib\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00falia Caroline Geib\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/\"},\"author\":{\"name\":\"J\u00falia Caroline Geib\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/147bcec9465f46cb386c31d3e27467d1\"},\"headline\":\"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria\",\"datePublished\":\"2020-09-06T17:59:44+00:00\",\"dateModified\":\"2020-09-06T18:11:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/\"},\"wordCount\":122,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg\",\"keywords\":[\"conven\u00e7\u00f5es\",\"PT\",\"Westf\u00e1lia\"],\"articleSection\":[\"Destaques\",\"Elei\u00e7\u00f5es\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/\",\"name\":\"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg\",\"datePublished\":\"2020-09-06T17:59:44+00:00\",\"dateModified\":\"2020-09-06T18:11:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/147bcec9465f46cb386c31d3e27467d1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg\",\"width\":800,\"height\":600,\"caption\":\"Spellmeier (e) e Docena \\\/ Cr\u00e9dito: Cleomar Trapp \\\/ divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2020\\\/09\\\/06\\\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/147bcec9465f46cb386c31d3e27467d1\",\"name\":\"J\u00falia Caroline Geib\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g\",\"caption\":\"J\u00falia Caroline Geib\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/juliacaroline-geib\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/","og_locale":"pt_BR","og_type":"article","og_title":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular","og_description":"O partido do PT realizou sua conven\u00e7\u00e3o na manh\u00e3 deste domingo (06\/09) em Westf\u00e1lia. Na ocasi\u00e3o, foi oficializada a candidatura do atual vereador Cl\u00e9cio Spellmeier (PT) como vice-prefeito do candidato a prefeito Joacir Ant\u00f4nio Docena (MDB). O MDB e o PDT, partidos coligados, realizaram suas conven\u00e7\u00f5es ontem. Os tr\u00eas partidos est\u00e3o aliados e compuseram a [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/","og_site_name":"Folha Popular","article_published_time":"2020-09-06T17:59:44+00:00","article_modified_time":"2020-09-06T18:11:16+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","type":"image\/jpeg"}],"author":"J\u00falia Caroline Geib","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"J\u00falia Caroline Geib","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/"},"author":{"name":"J\u00falia Caroline Geib","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/147bcec9465f46cb386c31d3e27467d1"},"headline":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria","datePublished":"2020-09-06T17:59:44+00:00","dateModified":"2020-09-06T18:11:16+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/"},"wordCount":122,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","keywords":["conven\u00e7\u00f5es","PT","Westf\u00e1lia"],"articleSection":["Destaques","Elei\u00e7\u00f5es","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/","url":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/","name":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","datePublished":"2020-09-06T17:59:44+00:00","dateModified":"2020-09-06T18:11:16+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/147bcec9465f46cb386c31d3e27467d1"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","width":800,"height":600,"caption":"Spellmeier (e) e Docena \/ Cr\u00e9dito: Cleomar Trapp \/ divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2020\/09\/06\/apos-convencao-saiba-quem-sao-os-candidatos-a-vereador-do-pt-de-westfalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Ap\u00f3s conven\u00e7\u00e3o, PT de Westf\u00e1lia define candidatos e confirma Joacir e Cl\u00e9cio na majorit\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/147bcec9465f46cb386c31d3e27467d1","name":"J\u00falia Caroline Geib","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d41face027c94e737c988dbe558b343c91dfb850c2d3934b6633e5a8b17c5c80?s=96&d=mm&r=g","caption":"J\u00falia Caroline Geib"},"url":"https:\/\/folhapopular.info\/index.php\/author\/juliacaroline-geib\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-06-at-14.54.53-e1599415126359.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/73297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/553"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=73297"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/73297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/73298"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=73297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=73297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=73297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}