{"id":89925,"date":"2021-09-23T15:17:31","date_gmt":"2021-09-23T18:17:31","guid":{"rendered":"https:\/\/folhapopular.info\/?p=89925"},"modified":"2021-09-23T15:17:34","modified_gmt":"2021-09-23T18:17:34","slug":"melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/","title":{"rendered":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Secretaria de Obras, Via\u00e7\u00e3o e Transportes, atrav\u00e9s da equipe do Departamento de Abastecimento de \u00c1gua, realizou o&nbsp;servi\u00e7o&nbsp;de reforma e amplia\u00e7\u00e3o da rede de \u00e1gua na Rua Duque de Caxias, localizada na Linha Germano, no Bairro Canabarro, a fim de dar mais vaz\u00e3o \u00e0 \u00e1gua e solucionar o problema de falta abastecimento que ocorria com frequ\u00eancia no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A demanda era uma reivindica\u00e7\u00e3o antiga dos moradores da localidade, visto que era muito comum ocorrer a falta de \u00e1gua em determinados hor\u00e1rios. A conclus\u00e3o dos servi\u00e7os ocorreu no final do m\u00eas de agosto.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-1024x683.jpg\" alt=\"\" data-id=\"89928\" data-link=\"https:\/\/folhapopular.info\/?attachment_id=89928\" class=\"wp-image-89928\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-1024x683.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-300x200.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-768x512.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-1536x1024.jpg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-2048x1365.jpg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-696x464.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-1068x712.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-1-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-1024x683.jpg\" alt=\"\" data-id=\"89929\" data-full-url=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-scaled.jpg\" data-link=\"https:\/\/folhapopular.info\/?attachment_id=89929\" class=\"wp-image-89929\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-1024x683.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-300x200.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-768x512.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-1536x1024.jpg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-2048x1365.jpg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-696x464.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-1068x712.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-2-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O prefeito Celso Alo\u00edsio Forneck ressaltou a import\u00e2ncia desta melhoria para a comunidade local. \u201cS\u00e3o pequenas a\u00e7\u00f5es, que n\u00e3o representam investimentos t\u00e3o grandiosos, mas que fazem a diferen\u00e7a na vida das pessoas. Por isso precisamos ouvir nossa popula\u00e7\u00e3o, saber o que realmente \u00e9 importante em cada comunidade.\u00a0Estamos felizes em poder resolver e entregar um servi\u00e7o de qualidade a estes moradores\u201d, enfatiza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Obras, Via\u00e7\u00e3o e Transportes, atrav\u00e9s da equipe do Departamento de Abastecimento de \u00c1gua, realizou o&nbsp;servi\u00e7o&nbsp;de reforma e amplia\u00e7\u00e3o da rede de \u00e1gua na Rua Duque de Caxias, localizada na Linha Germano, no Bairro Canabarro, a fim de dar mais vaz\u00e3o \u00e0 \u00e1gua e solucionar o problema de falta abastecimento que ocorria com [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":89927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[1629,1934,6988,26],"class_list":["post-89925","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-linha-germano","tag-melhorias","tag-rede-de-agua","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Secretaria de Obras, Via\u00e7\u00e3o e Transportes, atrav\u00e9s da equipe do Departamento de Abastecimento de \u00c1gua, realizou o&nbsp;servi\u00e7o&nbsp;de reforma e amplia\u00e7\u00e3o da rede de \u00e1gua na Rua Duque de Caxias, localizada na Linha Germano, no Bairro Canabarro, a fim de dar mais vaz\u00e3o \u00e0 \u00e1gua e solucionar o problema de falta abastecimento que ocorria com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T18:17:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-23T18:17:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento\",\"datePublished\":\"2021-09-23T18:17:31+00:00\",\"dateModified\":\"2021-09-23T18:17:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/\"},\"wordCount\":191,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg\",\"keywords\":[\"Linha Germano\",\"Melhorias\",\"Rede de \u00e1gua\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/\",\"name\":\"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg\",\"datePublished\":\"2021-09-23T18:17:31+00:00\",\"dateModified\":\"2021-09-23T18:17:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg\",\"width\":800,\"height\":533,\"caption\":\"Cr\u00e9ditos da foto: Diego Silva \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/23\\\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/","og_locale":"pt_BR","og_type":"article","og_title":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular","og_description":"A Secretaria de Obras, Via\u00e7\u00e3o e Transportes, atrav\u00e9s da equipe do Departamento de Abastecimento de \u00c1gua, realizou o&nbsp;servi\u00e7o&nbsp;de reforma e amplia\u00e7\u00e3o da rede de \u00e1gua na Rua Duque de Caxias, localizada na Linha Germano, no Bairro Canabarro, a fim de dar mais vaz\u00e3o \u00e0 \u00e1gua e solucionar o problema de falta abastecimento que ocorria com [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/","og_site_name":"Folha Popular","article_published_time":"2021-09-23T18:17:31+00:00","article_modified_time":"2021-09-23T18:17:34+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento","datePublished":"2021-09-23T18:17:31+00:00","dateModified":"2021-09-23T18:17:34+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/"},"wordCount":191,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","keywords":["Linha Germano","Melhorias","Rede de \u00e1gua","Teut\u00f4nia"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/","url":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/","name":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","datePublished":"2021-09-23T18:17:31+00:00","dateModified":"2021-09-23T18:17:34+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","width":800,"height":533,"caption":"Cr\u00e9ditos da foto: Diego Silva \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/23\/melhorias-na-rede-de-agua-da-linha-germano-em-teutonia-resolve-falta-de-abastecimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Melhorias na rede de \u00e1gua da Linha Germano, em Teut\u00f4nia, resolve falta de abastecimento"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/2021_09_23_Melhorias-na-rede-de-agua-da-Linha-Germana-resolve-falta-de-abastecimento-4-scaled-e1632419760545.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/89925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=89925"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/89925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/89927"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=89925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=89925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=89925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}