{"id":90326,"date":"2021-09-30T08:30:39","date_gmt":"2021-09-30T11:30:39","guid":{"rendered":"https:\/\/folhapopular.info\/?p=90326"},"modified":"2021-09-30T08:30:41","modified_gmt":"2021-09-30T11:30:41","slug":"jaque-weber-vence-3km-geral-em-santa-cruz-do-sul","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/","title":{"rendered":"Jaque Weber vence 3km geral em Santa Cruz do Sul"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A atleta da AMO\/Certel\/Languiru\/Languiru participou no \u00faltimo domingo da R\u00fastica Estadual de Santa Cruz do Sul. A prova marcou o retorno dos eventos presenciais de corrida no Vale do Rio Pardo e premiou os melhores nas dist\u00e2ncias dos 3km, 5km, 10km e meia maratona. Jaque venceu a dist\u00e2ncia mais curta no tempo de 10min30seg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Foi minha primeira prova depois do per\u00edodo de pico de 2021. J\u00e1 estamos em per\u00edodo de manuten\u00e7\u00e3o de performance, visando o pr\u00f3ximo ano. Foi um momento especial pois marcou um novo ciclo, ap\u00f3s um per\u00edodo de tratamento de um c\u00e2ncer que meu namorado e treinador, Fabiano Pe\u00e7anha enfrentou. E neste momento, competir em casa e poder comemorar a sa\u00fade \u00e9 nossa principal vit\u00f3ria&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No final de outubro, Jaque compete o Campeonato Estadual de Atletismo em Porto Alegre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A atleta da AMO\/Certel\/Languiru\/Languiru participou no \u00faltimo domingo da R\u00fastica Estadual de Santa Cruz do Sul. A prova marcou o retorno dos eventos presenciais de corrida no Vale do Rio Pardo e premiou os melhores nas dist\u00e2ncias dos 3km, 5km, 10km e meia maratona. Jaque venceu a dist\u00e2ncia mais curta no tempo de 10min30seg. &#8220;Foi [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":90327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,5],"tags":[2323,4939,26],"class_list":["post-90326","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-esportes","tag-corrida","tag-jaque-weber","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A atleta da AMO\/Certel\/Languiru\/Languiru participou no \u00faltimo domingo da R\u00fastica Estadual de Santa Cruz do Sul. A prova marcou o retorno dos eventos presenciais de corrida no Vale do Rio Pardo e premiou os melhores nas dist\u00e2ncias dos 3km, 5km, 10km e meia maratona. Jaque venceu a dist\u00e2ncia mais curta no tempo de 10min30seg. &#8220;Foi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T11:30:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T11:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Jaque Weber vence 3km geral em Santa Cruz do Sul\",\"datePublished\":\"2021-09-30T11:30:39+00:00\",\"dateModified\":\"2021-09-30T11:30:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/\"},\"wordCount\":156,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg\",\"keywords\":[\"Corrida\",\"Jaque Weber\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Esportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/\",\"name\":\"Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg\",\"datePublished\":\"2021-09-30T11:30:39+00:00\",\"dateModified\":\"2021-09-30T11:30:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg\",\"width\":800,\"height\":533,\"caption\":\"Jaque venceu a dist\u00e2ncia de 3km \\\/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/09\\\/30\\\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jaque Weber vence 3km geral em Santa Cruz do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/","og_locale":"pt_BR","og_type":"article","og_title":"Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular","og_description":"A atleta da AMO\/Certel\/Languiru\/Languiru participou no \u00faltimo domingo da R\u00fastica Estadual de Santa Cruz do Sul. A prova marcou o retorno dos eventos presenciais de corrida no Vale do Rio Pardo e premiou os melhores nas dist\u00e2ncias dos 3km, 5km, 10km e meia maratona. Jaque venceu a dist\u00e2ncia mais curta no tempo de 10min30seg. &#8220;Foi [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/","og_site_name":"Folha Popular","article_published_time":"2021-09-30T11:30:39+00:00","article_modified_time":"2021-09-30T11:30:41+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Jaque Weber vence 3km geral em Santa Cruz do Sul","datePublished":"2021-09-30T11:30:39+00:00","dateModified":"2021-09-30T11:30:41+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/"},"wordCount":156,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","keywords":["Corrida","Jaque Weber","Teut\u00f4nia"],"articleSection":["Destaques","Esportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/","url":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/","name":"Jaque Weber vence 3km geral em Santa Cruz do Sul - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","datePublished":"2021-09-30T11:30:39+00:00","dateModified":"2021-09-30T11:30:41+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","width":800,"height":533,"caption":"Jaque venceu a dist\u00e2ncia de 3km \/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2021\/09\/30\/jaque-weber-vence-3km-geral-em-santa-cruz-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Jaque Weber vence 3km geral em Santa Cruz do Sul"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/09\/f0dd7f8b-dd04-42e0-94b9-74028bcb676f-e1633001281773.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/90326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=90326"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/90326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/90327"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=90326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=90326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=90326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}