{"id":93529,"date":"2021-11-29T16:42:46","date_gmt":"2021-11-29T19:42:46","guid":{"rendered":"https:\/\/folhapopular.info\/?p=93529"},"modified":"2021-11-29T16:42:51","modified_gmt":"2021-11-29T19:42:51","slug":"noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/","title":{"rendered":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">As tr\u00eas d\u00e9cadas de hist\u00f3ria do N\u00facleo Municipal de Cultura foram relembrados e comemorados na sexta-feira \u00e0 noite (26\/11) na presen\u00e7a de autoridades, representantes das entidades e comunidade em geral. O momento foi de homenagens e agradecimentos a pessoas que de alguma forma colaboraram e atuaram junto ao N\u00facleo de Cultura ao longo destes 30 anos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-1024x683.jpg\" alt=\"\" class=\"wp-image-93531\" width=\"402\" height=\"268\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-1024x683.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-300x200.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-768x512.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-1536x1024.jpg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-2048x1365.jpg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-696x464.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-1068x712.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1491-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><figcaption><em>Centenas de pessoas prestigiaram o evento em comemora\u00e7\u00e3o aos 30 anos da entidade<\/em> \/ Cr\u00e9dito da foto: Daiane La\u00eds Kalsing \/ Divulga\u00e7\u00e3o<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Realizado na quadra coberta da Pra\u00e7a Flores da Cunha, o p\u00fablico pode prestigiar as apresenta\u00e7\u00f5es culturais do Coral Municipal de Arroio do Meio (Comam), Grupo Teatral FoiceAcena, Grupo de Dan\u00e7as Helmuth Kuhn, Grupo Folcl\u00f3rico Alem\u00e3o Frohsinn, Schtena Big Band e CTG Quer\u00eancia do Arroio do Meio.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-1024x683.jpg\" alt=\"\" class=\"wp-image-93532\" width=\"381\" height=\"253\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-1024x683.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-300x200.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-768x512.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-1536x1024.jpg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-2048x1365.jpg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-696x464.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-1068x712.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1531-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 381px) 100vw, 381px\" \/><figcaption><em>Tradicionalismo esteve evidenciado pelo CTG Quer\u00eancia do Arroio do Meio<\/em> \/ Cr\u00e9dito da foto: Daiane La\u00eds Kalsing \/ Divulga\u00e7\u00e3o <\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Na ocasi\u00e3o foram homenageados os associados fundadores do N\u00facleo Municipal de Cultura, a primeira diretoria da entidade, secret\u00e1rios de Educa\u00e7\u00e3o, coordenadores de Cultura e os presidentes de todas as gest\u00f5es. Atual presidente da entidade, Alice Forneck ressaltou que o objetivo da noite eram tr\u00eas: mem\u00f3rias, homenagens e cultura. Saudou ainda os prefeitos, secret\u00e1rios de Educa\u00e7\u00e3o e presidentes do N\u00facleo de Cultura que contribu\u00edram para essa hist\u00f3ria de 30 anos. \u201cVale a pena investir na cultura e isso as nossas Administra\u00e7\u00f5es est\u00e3o fazendo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O prefeito Danilo Bruxel se mostrou satisfeito por ver que desde a funda\u00e7\u00e3o da entidade at\u00e9 os dias atuais, as Administra\u00e7\u00f5es deram o devido valor a este setor t\u00e3o importante. \u201cArroio do Meio tem uma hist\u00f3ria muito bonita, pois todas as administra\u00e7\u00f5es pensam no seu povo, na sua cultura e investem em sua qualidade de vida\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As tr\u00eas d\u00e9cadas de hist\u00f3ria do N\u00facleo Municipal de Cultura foram relembrados e comemorados na sexta-feira \u00e0 noite (26\/11) na presen\u00e7a de autoridades, representantes das entidades e comunidade em geral. O momento foi de homenagens e agradecimentos a pessoas que de alguma forma colaboraram e atuaram junto ao N\u00facleo de Cultura ao longo destes 30 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":93530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[140,3575],"class_list":["post-93529","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-arroio-do-meio","tag-homenagens","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"As tr\u00eas d\u00e9cadas de hist\u00f3ria do N\u00facleo Municipal de Cultura foram relembrados e comemorados na sexta-feira \u00e0 noite (26\/11) na presen\u00e7a de autoridades, representantes das entidades e comunidade em geral. O momento foi de homenagens e agradecimentos a pessoas que de alguma forma colaboraram e atuaram junto ao N\u00facleo de Cultura ao longo destes 30 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T19:42:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-29T19:42:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio\",\"datePublished\":\"2021-11-29T19:42:46+00:00\",\"dateModified\":\"2021-11-29T19:42:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/\"},\"wordCount\":361,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG_1515-scaled-e1638214782376.jpg\",\"keywords\":[\"Arroio do Meio\",\"Homenagens\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/\",\"name\":\"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG_1515-scaled-e1638214782376.jpg\",\"datePublished\":\"2021-11-29T19:42:46+00:00\",\"dateModified\":\"2021-11-29T19:42:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG_1515-scaled-e1638214782376.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG_1515-scaled-e1638214782376.jpg\",\"width\":800,\"height\":533,\"caption\":\"Presidentes de todas as gest\u00f5es foram homenageados \\\/ Cr\u00e9dito da foto: Daiane La\u00eds Kalsing \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2021\\\/11\\\/29\\\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/","og_locale":"pt_BR","og_type":"article","og_title":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular","og_description":"As tr\u00eas d\u00e9cadas de hist\u00f3ria do N\u00facleo Municipal de Cultura foram relembrados e comemorados na sexta-feira \u00e0 noite (26\/11) na presen\u00e7a de autoridades, representantes das entidades e comunidade em geral. O momento foi de homenagens e agradecimentos a pessoas que de alguma forma colaboraram e atuaram junto ao N\u00facleo de Cultura ao longo destes 30 [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/","og_site_name":"Folha Popular","article_published_time":"2021-11-29T19:42:46+00:00","article_modified_time":"2021-11-29T19:42:51+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio","datePublished":"2021-11-29T19:42:46+00:00","dateModified":"2021-11-29T19:42:51+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/"},"wordCount":361,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","keywords":["Arroio do Meio","Homenagens"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/","url":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/","name":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","datePublished":"2021-11-29T19:42:46+00:00","dateModified":"2021-11-29T19:42:51+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","width":800,"height":533,"caption":"Presidentes de todas as gest\u00f5es foram homenageados \/ Cr\u00e9dito da foto: Daiane La\u00eds Kalsing \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2021\/11\/29\/noite-de-homenagens-e-apresentacoes-marca-os-30-anos-do-nucleo-municipal-de-cultura-de-arroio-do-meio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Noite de homenagens e apresenta\u00e7\u00f5es marca os 30 anos do N\u00facleo Municipal de Cultura de Arroio do Meio"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2021\/11\/IMG_1515-scaled-e1638214782376.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/93529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=93529"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/93529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/93530"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=93529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=93529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=93529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}