{"id":97425,"date":"2022-01-26T16:40:33","date_gmt":"2022-01-26T19:40:33","guid":{"rendered":"https:\/\/folhapopular.info\/?p=97425"},"modified":"2022-01-26T16:48:36","modified_gmt":"2022-01-26T19:48:36","slug":"brigada-militar-captura-dois-foragidos-em-teutonia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/","title":{"rendered":"Brigada Militar captura dois foragidos em Teut\u00f4nia"},"content":{"rendered":"\n<p>Durante a manh\u00e3 desta quarta-feira (26\/1), a Brigada Militar efetuou a pris\u00e3o de dois indiv\u00edduos em Teut\u00f4nia. Eles estavam em situa\u00e7\u00e3o de foragido do sistemas prisional e possuem extensa ficha de antecedentes criminais. Os homens t\u00eam 21 e 26 anos de idade.<br><br>Conforme o 40\u00b0 BPM, por volta das 7h40min, durante patrulhamento de rotina, a guarni\u00e7\u00e3o de servi\u00e7o avistou um indiv\u00edduo em atitude suspeita na Estrada Velha. Ao realizar abordagem e procedimento de identifica\u00e7\u00e3o, constatou-se que homem (21) estava foragido do sistema prisional, com a tornozeleira eletr\u00f4nica rompida. Imediatamente, ele recebeu voz de pris\u00e3o.<br><br>Diante dos fatos, a Brigada Militar mobilizou viaturas e efetuou buscas na cidade por um segundo indiv\u00edduo, que tamb\u00e9m estaria foragido e morando com o homem preso anteriormente. Por volta das 11h, o segundo indiv\u00edduo se apresentou ao quartel da Brigada Militar e, por seguinte, recebeu voz de pris\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a manh\u00e3 desta quarta-feira (26\/1), a Brigada Militar efetuou a pris\u00e3o de dois indiv\u00edduos em Teut\u00f4nia. Eles estavam em situa\u00e7\u00e3o de foragido do sistemas prisional e possuem extensa ficha de antecedentes criminais. Os homens t\u00eam 21 e 26 anos de idade. Conforme o 40\u00b0 BPM, por volta das 7h40min, durante patrulhamento de rotina, a [&hellip;]<\/p>\n","protected":false},"author":625,"featured_media":97430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,7],"tags":[251,106,113],"class_list":{"0":"post-97425","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-geral","8":"category-seguranca","9":"tag-brigada-militar","10":"tag-policia","11":"tag-transito","12":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Durante a manh\u00e3 desta quarta-feira (26\/1), a Brigada Militar efetuou a pris\u00e3o de dois indiv\u00edduos em Teut\u00f4nia. Eles estavam em situa\u00e7\u00e3o de foragido do sistemas prisional e possuem extensa ficha de antecedentes criminais. Os homens t\u00eam 21 e 26 anos de idade. Conforme o 40\u00b0 BPM, por volta das 7h40min, durante patrulhamento de rotina, a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-26T19:40:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-26T19:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ed Moreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ed Moreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/\"},\"author\":{\"name\":\"Ed Moreira\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\"},\"headline\":\"Brigada Militar captura dois foragidos em Teut\u00f4nia\",\"datePublished\":\"2022-01-26T19:40:33+00:00\",\"dateModified\":\"2022-01-26T19:48:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/\"},\"wordCount\":162,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg\",\"keywords\":[\"Brigada Militar\",\"Pol\u00edcia\",\"Tr\u00e2nsito\"],\"articleSection\":[\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/\",\"name\":\"Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg\",\"datePublished\":\"2022-01-26T19:40:33+00:00\",\"dateModified\":\"2022-01-26T19:48:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg\",\"width\":1280,\"height\":705,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/26\\\/brigada-militar-captura-dois-foragidos-em-teutonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brigada Militar captura dois foragidos em Teut\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\",\"name\":\"Ed Moreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"caption\":\"Ed Moreira\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/edandreickgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/","og_locale":"pt_BR","og_type":"article","og_title":"Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular","og_description":"Durante a manh\u00e3 desta quarta-feira (26\/1), a Brigada Militar efetuou a pris\u00e3o de dois indiv\u00edduos em Teut\u00f4nia. Eles estavam em situa\u00e7\u00e3o de foragido do sistemas prisional e possuem extensa ficha de antecedentes criminais. Os homens t\u00eam 21 e 26 anos de idade. Conforme o 40\u00b0 BPM, por volta das 7h40min, durante patrulhamento de rotina, a [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/","og_site_name":"Folha Popular","article_published_time":"2022-01-26T19:40:33+00:00","article_modified_time":"2022-01-26T19:48:36+00:00","og_image":[{"width":1280,"height":705,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","type":"image\/jpeg"}],"author":"Ed Moreira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ed Moreira","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/"},"author":{"name":"Ed Moreira","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e"},"headline":"Brigada Militar captura dois foragidos em Teut\u00f4nia","datePublished":"2022-01-26T19:40:33+00:00","dateModified":"2022-01-26T19:48:36+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/"},"wordCount":162,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","keywords":["Brigada Militar","Pol\u00edcia","Tr\u00e2nsito"],"articleSection":["Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/","name":"Brigada Militar captura dois foragidos em Teut\u00f4nia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","datePublished":"2022-01-26T19:40:33+00:00","dateModified":"2022-01-26T19:48:36+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","width":1280,"height":705,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/26\/brigada-militar-captura-dois-foragidos-em-teutonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Brigada Militar captura dois foragidos em Teut\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e","name":"Ed Moreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","caption":"Ed Moreira"},"url":"https:\/\/folhapopular.info\/index.php\/author\/edandreickgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-26-at-15.38.34-1.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/97425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/625"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=97425"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/97425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/97430"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=97425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=97425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=97425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}