{"id":97648,"date":"2022-01-31T11:11:24","date_gmt":"2022-01-31T14:11:24","guid":{"rendered":"https:\/\/folhapopular.info\/?p=97648"},"modified":"2022-01-31T11:20:01","modified_gmt":"2022-01-31T14:20:01","slug":"mulher-e-assaltada-no-bairro-campestre-em-lajeado","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/","title":{"rendered":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado"},"content":{"rendered":"\n<p>Uma mulher foi assaltada na noite do \u00faltimo s\u00e1bado (29), no Bairro Campestre, em Lajeado. O fato se deu por volta das 19h30min, quando ela estacionava seu GM Celta e foi cercada por dois indiv\u00edduos, que lhe apontaram uma arma na cabe\u00e7a e exigiram a entrega de seus pertencentes: carteira, portando documentos, cart\u00f5es e aproximadamente R$ 120 em esp\u00e9cie), al\u00e9m de dois celulares.<\/p>\n\n\n\n<p>De acordo com o boletim de ocorr\u00eancia, eles fugiram com o ve\u00edculo da v\u00edtima. No dia seguinte, ela recebeu uma liga\u00e7\u00e3o de um indiv\u00edduo que teria localizado seus documentos pr\u00f3ximo a um ve\u00edculo, que estaria estacionado no Bairro Bela Vista, em Arroio do Meio. Ele disse ser morador do local e ter identificado a v\u00edtima atrav\u00e9s de uma postagem de roubo no Facebook. Segundo ele, o Celta estava trancado e foi necess\u00e1rio utiliza\u00e7\u00e3o de uma chave reserva para abrir o ve\u00edculo e entreg\u00e1-lo na Delegacia de Pol\u00edcia de Pronto Atendimento de Lajeado.<\/p>\n\n\n\n<p>O dinheiro e os telefones celulares n\u00e3o foram recuperados.<\/p>\n\n\n\n<p>Ao longo do fim de semana, tamb\u00e9m foram efetuadas pris\u00f5es por tr\u00e1fico de entorpecentes nos munic\u00edpios de Teut\u00f4nia, Lajeado e Arroio do Meio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher foi assaltada na noite do \u00faltimo s\u00e1bado (29), no Bairro Campestre, em Lajeado. O fato se deu por volta das 19h30min, quando ela estacionava seu GM Celta e foi cercada por dois indiv\u00edduos, que lhe apontaram uma arma na cabe\u00e7a e exigiram a entrega de seus pertencentes: carteira, portando documentos, cart\u00f5es e aproximadamente [&hellip;]<\/p>\n","protected":false},"author":625,"featured_media":58539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[106,478,2528,1345],"class_list":{"0":"post-97648","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seguranca","8":"tag-policia","9":"tag-roubo","10":"tag-roubo-de-veiculo","11":"tag-veiculo","12":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Uma mulher foi assaltada na noite do \u00faltimo s\u00e1bado (29), no Bairro Campestre, em Lajeado. O fato se deu por volta das 19h30min, quando ela estacionava seu GM Celta e foi cercada por dois indiv\u00edduos, que lhe apontaram uma arma na cabe\u00e7a e exigiram a entrega de seus pertencentes: carteira, portando documentos, cart\u00f5es e aproximadamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T14:11:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-31T14:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ed Moreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ed Moreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/\"},\"author\":{\"name\":\"Ed Moreira\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\"},\"headline\":\"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado\",\"datePublished\":\"2022-01-31T14:11:24+00:00\",\"dateModified\":\"2022-01-31T14:20:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/\"},\"wordCount\":219,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"keywords\":[\"Pol\u00edcia\",\"Roubo\",\"Roubo de ve\u00edculo\",\"Ve\u00edculo\"],\"articleSection\":[\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/\",\"name\":\"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"datePublished\":\"2022-01-31T14:11:24+00:00\",\"dateModified\":\"2022-01-31T14:20:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Pol\u00edcia-e1567961556849.jpg\",\"width\":800,\"height\":563,\"caption\":\"Cr\u00e9dito da arte: J\u00falia Caroline Geib\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/01\\\/31\\\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e271c6e0b26128fa94cfaf17cc9e063e\",\"name\":\"Ed Moreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g\",\"caption\":\"Ed Moreira\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/edandreickgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/","og_locale":"pt_BR","og_type":"article","og_title":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular","og_description":"Uma mulher foi assaltada na noite do \u00faltimo s\u00e1bado (29), no Bairro Campestre, em Lajeado. O fato se deu por volta das 19h30min, quando ela estacionava seu GM Celta e foi cercada por dois indiv\u00edduos, que lhe apontaram uma arma na cabe\u00e7a e exigiram a entrega de seus pertencentes: carteira, portando documentos, cart\u00f5es e aproximadamente [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/","og_site_name":"Folha Popular","article_published_time":"2022-01-31T14:11:24+00:00","article_modified_time":"2022-01-31T14:20:01+00:00","og_image":[{"width":800,"height":563,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","type":"image\/jpeg"}],"author":"Ed Moreira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ed Moreira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/"},"author":{"name":"Ed Moreira","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e"},"headline":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado","datePublished":"2022-01-31T14:11:24+00:00","dateModified":"2022-01-31T14:20:01+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/"},"wordCount":219,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","keywords":["Pol\u00edcia","Roubo","Roubo de ve\u00edculo","Ve\u00edculo"],"articleSection":["Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/","name":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","datePublished":"2022-01-31T14:11:24+00:00","dateModified":"2022-01-31T14:20:01+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","width":800,"height":563,"caption":"Cr\u00e9dito da arte: J\u00falia Caroline Geib"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/01\/31\/mulher-e-assaltada-no-bairro-campestre-em-lajeado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Mulher \u00e9 assaltada no Bairro Campestre, em Lajeado"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e271c6e0b26128fa94cfaf17cc9e063e","name":"Ed Moreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9274330291ac9c6c66742317f29501071e72f6aa312c5fa2db351130adc72a97?s=96&d=mm&r=g","caption":"Ed Moreira"},"url":"https:\/\/folhapopular.info\/index.php\/author\/edandreickgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Pol\u00edcia-e1567961556849.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/97648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/625"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=97648"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/97648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/58539"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=97648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=97648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=97648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}