{"id":4227,"count":20,"description":"","link":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/","name":"Dia Internacional da Mulher","slug":"dia-internacional-da-mulher","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Dia Internacional da Mulher - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Dia Internacional da Mulher - Folha Popular\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/tag\\\/dia-internacional-da-mulher\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/tag\\\/dia-internacional-da-mulher\\\/\",\"name\":\"Arquivos Dia Internacional da Mulher - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/tag\\\/dia-internacional-da-mulher\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/tag\\\/dia-internacional-da-mulher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia Internacional da Mulher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Dia Internacional da Mulher - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Dia Internacional da Mulher - Folha Popular","og_url":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/","og_site_name":"Folha Popular","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/","url":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/","name":"Arquivos Dia Internacional da Mulher - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/tag\/dia-internacional-da-mulher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Dia Internacional da Mulher"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags\/4227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts?tags=4227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}